{"id":1536,"date":"2023-08-15T10:08:34","date_gmt":"2023-08-15T08:08:34","guid":{"rendered":"https:\/\/regbu.com\/?p=1536"},"modified":"2025-09-05T07:39:37","modified_gmt":"2025-09-05T05:39:37","slug":"svedska-skupina-abba-si-podmanila-svet","status":"publish","type":"post","link":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/","title":{"rendered":"Le groupe su\u00e9dois ABBA a conquis le monde"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Le groupe su\u00e9dois ABBA a connu une popularit\u00e9 mondiale en son temps, tout comme le groupe <strong><a href=\"https:\/\/regbu.com\/fr\/pink-floyd-et-leur-rock-psychedelique\/\">Pink Floyd<\/a><\/strong>. Pour beaucoup, c'est l'un des groupes les plus r\u00e9ussis du genre que la pop est devenue. Largement accompagn\u00e9 par <em>le pop rock, le glam rock et les \u00e9l\u00e9ments propres au disco<\/em>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fond\u00e9e en 1972<\/li>\n\n\n\n<li>Lieu de fondation Stockholm<\/li>\n\n\n\n<li>Des centaines de millions de disques vendus<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Vous vous demandez peut-\u00eatre quel est le nom de ce groupe de musique ? Il s'agit des lettres initiales des quatre membres, \u00e0 savoir Agnetha, Bj\u00f6rn, Benny et Anni-Frid. Le nom ABBA est d\u00e9sormais ancr\u00e9 dans l'esprit de nombreux amateurs de musique de qualit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les d\u00e9buts en 1970<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les concerts de 1970 ont pr\u00e9c\u00e9d\u00e9 le d\u00e9but de la collaboration officielle du groupe. \u00c0 l'\u00e9poque, c'\u00e9tait sur la plage, devant les soldats de l'ONU. C'\u00e9tait un \u00e9v\u00e9nement Festfolk. Ce n'est qu'ensuite que les enregistrements communs ont suivi. <strong>Le groupe su\u00e9dois ABBA<\/strong> ses ann\u00e9es d'activit\u00e9 s'\u00e9tendent de 1972 \u00e0 1982. Puis, seulement depuis 2016, date d'un certain retour en force.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le groupe su\u00e9dois ABBA en questions et r\u00e9ponses<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Rejoignez-nous pour vous rem\u00e9morer les plus grandes r\u00e9alisations du groupe. Des chansons comme <strong>Les gens ont besoin d'amour et il est votre fr\u00e8re <\/strong>...de 1972 est un must que tout le monde doit conna\u00eetre. Le groupe su\u00e9dois ABBA a en effet sorti plus d'un album studio et de compilations. Les questions et r\u00e9ponses ci-dessous vous permettront de vous en convaincre.<\/p>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1692259503253\"><strong class=\"schema-faq-question\">Quels sont les albums c\u00e9l\u00e8bres sortis avant 1977 ?<\/strong> <p class=\"schema-faq-answer\">Les albums \u00e9taient Ring Ring, Waterloo, ABBA, Arrival et The Album.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1692259509855\"><strong class=\"schema-faq-question\">Quels sont les albums que le groupe a sortis apr\u00e8s 1977 ?<\/strong> <p class=\"schema-faq-answer\">Tout a commenc\u00e9 en 1979 avec l'album Voulez-Vous. Il a \u00e9t\u00e9 suivi par des albums comme Super Trouper, The Visitors et enfin Voyage en 2011.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1692259520352\"><strong class=\"schema-faq-question\">Quelle a \u00e9t\u00e9 la derni\u00e8re compilation du groupe ?<\/strong> <p class=\"schema-faq-answer\">Cette compilation de 1982 s'intitule The Singles : The First Ten Years.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1692259527820\"><strong class=\"schema-faq-question\">Quelles sont les autres chansons c\u00e9l\u00e8bres et populaires ?<\/strong> <p class=\"schema-faq-answer\">Il ne faut pas oublier les chansons Ring, Ring, Fernando, Does Your Mother Know, Honey, Honey et Lay All Your Love On Me.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1692259535224\"><strong class=\"schema-faq-question\">Quels sont les prix remport\u00e9s par ABBA ?<\/strong> <p class=\"schema-faq-answer\">Il convient de mentionner Rockbj\u00f6rnen pour le groupe\/artiste su\u00e9dois du si\u00e8cle en 1999 et Musikexportpriset en 2021.<\/p> <\/div> <\/div>","protected":false},"excerpt":{"rendered":"<p>Le groupe su\u00e9dois ABBA a atteint une popularit\u00e9 mondiale en son temps, tout comme Pink Floyd. Pour beaucoup, c'est l'un des groupes les plus r\u00e9ussis du genre que la pop est devenue. Largement accompagn\u00e9 de pop rock, de glam rock et d'\u00e9l\u00e9ments appropri\u00e9s de disco. Vous vous demandez peut-\u00eatre ce qui a donn\u00e9 son nom \u00e0 ce groupe ? C'est ... <\/p>","protected":false},"author":2,"featured_media":1537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[1914,136,1921,1918,111,1916,1917,1915,1922,1920],"class_list":["post-1536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hudba","tag-abba","tag-kapela","tag-lay-all-your-love-on-me","tag-people-need-love","tag-pop","tag-skupina-hudba","tag-stockholm","tag-svedska-skupina-abba","tag-voulez-vous","tag-voyage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0160v\u00e9dsk\u00e1 skupina ABBA si podmanila sv\u011bt - REGBU.COM<\/title>\n<meta name=\"description\" content=\"\u0160v\u00e9dsk\u00e1 skupina ABBA se proslavila po cel\u00e9m sv\u011bt\u011b. Zn\u00e1te jej\u00ed prvopo\u010d\u00e1tky vzniku a ty nejv\u011bt\u0161\u00ed hity? Prozrad\u00edme V\u00e1m, jak\u00e9 to jsou.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0160v\u00e9dsk\u00e1 skupina ABBA si podmanila sv\u011bt - REGBU.COM\" \/>\n<meta property=\"og:description\" content=\"\u0160v\u00e9dsk\u00e1 skupina ABBA se proslavila po cel\u00e9m sv\u011bt\u011b. Zn\u00e1te jej\u00ed prvopo\u010d\u00e1tky vzniku a ty nejv\u011bt\u0161\u00ed hity? Prozrad\u00edme V\u00e1m, jak\u00e9 to jsou.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/\" \/>\n<meta property=\"og:site_name\" content=\"REGBU.COM\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-15T08:08:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T05:39:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regbu.com\/wp-content\/uploads\/2023\/08\/svedska-skupina-abba-si-podmanila-svet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"677\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"George Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"George Martin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/\"},\"author\":{\"name\":\"George Martin\",\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#\\\/schema\\\/person\\\/94ea9deda2629771b8a9ced002f6784e\"},\"headline\":\"\u0160v\u00e9dsk\u00e1 skupina ABBA si podmanila sv\u011bt\",\"datePublished\":\"2023-08-15T08:08:34+00:00\",\"dateModified\":\"2025-09-05T05:39:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/\"},\"wordCount\":413,\"image\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/svedska-skupina-abba-si-podmanila-svet.jpg\",\"keywords\":[\"abba\",\"kapela\",\"Lay All Your Love On Me\",\"People Need Love\",\"pop\",\"skupina hudba\",\"stockholm\",\"\u0161v\u00e9dsk\u00e1 skupina abba\",\"Voulez-Vous\",\"Voyage\"],\"articleSection\":[\"Hudba\"],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/\",\"url\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/\",\"name\":\"\u0160v\u00e9dsk\u00e1 skupina ABBA si podmanila sv\u011bt - REGBU.COM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/svedska-skupina-abba-si-podmanila-svet.jpg\",\"datePublished\":\"2023-08-15T08:08:34+00:00\",\"dateModified\":\"2025-09-05T05:39:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#\\\/schema\\\/person\\\/94ea9deda2629771b8a9ced002f6784e\"},\"description\":\"\u0160v\u00e9dsk\u00e1 skupina ABBA se proslavila po cel\u00e9m sv\u011bt\u011b. Zn\u00e1te jej\u00ed prvopo\u010d\u00e1tky vzniku a ty nejv\u011bt\u0161\u00ed hity? Prozrad\u00edme V\u00e1m, jak\u00e9 to jsou.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259503253\"},{\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259509855\"},{\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259520352\"},{\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259527820\"},{\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259535224\"}],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/svedska-skupina-abba-si-podmanila-svet.jpg\",\"contentUrl\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/svedska-skupina-abba-si-podmanila-svet.jpg\",\"width\":1200,\"height\":677,\"caption\":\"\u0160v\u00e9dsk\u00e1 skupina ABBA si podmanila sv\u011bt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/regbu.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0160v\u00e9dsk\u00e1 skupina ABBA si podmanila sv\u011bt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/regbu.com\\\/en\\\/\",\"name\":\"REGBU.COM\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regbu.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#\\\/schema\\\/person\\\/94ea9deda2629771b8a9ced002f6784e\",\"name\":\"George Martin\",\"url\":\"https:\\\/\\\/regbu.com\\\/fr\\\/author\\\/george-martin\\\/\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259503253\",\"position\":1,\"url\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259503253\",\"name\":\"Jak\u00e1 slavn\u00e1 alba vych\u00e1zela do roku 1977?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Byla to hudebn\u00ed alba Ring Ring, Waterloo, ABBA, Arrival a The Album.\",\"inLanguage\":\"fr-FR\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259509855\",\"position\":2,\"url\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259509855\",\"name\":\"Jak\u00e1 alba vydala kapela po roce 1977?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"V\u0161e za\u010dalo v roce 1979 albem Voulez-Vous. N\u00e1sledovala alba jako Super Trouper, The Visitors a v neposledn\u00ed \u0159ad\u011b Voyage z roku 2011.\",\"inLanguage\":\"fr-FR\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259520352\",\"position\":3,\"url\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259520352\",\"name\":\"Jak\u00e1 byla posledn\u00ed kompilace kapely?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Tato kompilace z roku 1982 nesla n\u00e1zev The Singles: The First Ten Years.\",\"inLanguage\":\"fr-FR\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259527820\",\"position\":4,\"url\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259527820\",\"name\":\"Jak\u00e9 dal\u0161\u00ed p\u00edsn\u011b pat\u0159\u00ed mezi slavn\u00e9 a popul\u00e1rn\u00ed?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Zapom\u00ednat bychom nem\u011bli na p\u00edsn\u011b Ring, Ring, Fernando, Does Your Mother Know, Honey, Honey a Lay All Your Love On Me.\",\"inLanguage\":\"fr-FR\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259535224\",\"position\":5,\"url\":\"https:\\\/\\\/regbu.com\\\/fr\\\/le-groupe-suedois-abba-a-conquis-le-monde\\\/#faq-question-1692259535224\",\"name\":\"Jak\u00e1 ocen\u011bn\u00ed kapela ABBA z\u00edskala?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Zm\u00ednka mus\u00ed padnout o Rockbj\u00f6rnen for the century's Swedish group\\\/artist z roku 1999 a Musikexportpriset z roku 2021.\",\"inLanguage\":\"fr-FR\"},\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le groupe su\u00e9dois ABBA a conquis le monde - REGBU.COM","description":"Le groupe su\u00e9dois ABBA est devenu c\u00e9l\u00e8bre dans le monde entier. Connaissez-vous les origines du groupe et ses plus grands succ\u00e8s ? Nous allons vous dire de quoi il s'agit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/","og_locale":"fr_FR","og_type":"article","og_title":"\u0160v\u00e9dsk\u00e1 skupina ABBA si podmanila sv\u011bt - REGBU.COM","og_description":"\u0160v\u00e9dsk\u00e1 skupina ABBA se proslavila po cel\u00e9m sv\u011bt\u011b. Zn\u00e1te jej\u00ed prvopo\u010d\u00e1tky vzniku a ty nejv\u011bt\u0161\u00ed hity? Prozrad\u00edme V\u00e1m, jak\u00e9 to jsou.","og_url":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/","og_site_name":"REGBU.COM","article_published_time":"2023-08-15T08:08:34+00:00","article_modified_time":"2025-09-05T05:39:37+00:00","og_image":[{"width":1200,"height":677,"url":"https:\/\/regbu.com\/wp-content\/uploads\/2023\/08\/svedska-skupina-abba-si-podmanila-svet.jpg","type":"image\/jpeg"}],"author":"George Martin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"George Martin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#article","isPartOf":{"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/"},"author":{"name":"George Martin","@id":"https:\/\/regbu.com\/en\/#\/schema\/person\/94ea9deda2629771b8a9ced002f6784e"},"headline":"\u0160v\u00e9dsk\u00e1 skupina ABBA si podmanila sv\u011bt","datePublished":"2023-08-15T08:08:34+00:00","dateModified":"2025-09-05T05:39:37+00:00","mainEntityOfPage":{"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/"},"wordCount":413,"image":{"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/regbu.com\/wp-content\/uploads\/2023\/08\/svedska-skupina-abba-si-podmanila-svet.jpg","keywords":["abba","kapela","Lay All Your Love On Me","People Need Love","pop","skupina hudba","stockholm","\u0161v\u00e9dsk\u00e1 skupina abba","Voulez-Vous","Voyage"],"articleSection":["Hudba"],"inLanguage":"fr-FR"},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/","url":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/","name":"Le groupe su\u00e9dois ABBA a conquis le monde - REGBU.COM","isPartOf":{"@id":"https:\/\/regbu.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#primaryimage"},"image":{"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/regbu.com\/wp-content\/uploads\/2023\/08\/svedska-skupina-abba-si-podmanila-svet.jpg","datePublished":"2023-08-15T08:08:34+00:00","dateModified":"2025-09-05T05:39:37+00:00","author":{"@id":"https:\/\/regbu.com\/en\/#\/schema\/person\/94ea9deda2629771b8a9ced002f6784e"},"description":"Le groupe su\u00e9dois ABBA est devenu c\u00e9l\u00e8bre dans le monde entier. Connaissez-vous les origines du groupe et ses plus grands succ\u00e8s ? Nous allons vous dire de quoi il s'agit.","breadcrumb":{"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259503253"},{"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259509855"},{"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259520352"},{"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259527820"},{"@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259535224"}],"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#primaryimage","url":"https:\/\/regbu.com\/wp-content\/uploads\/2023\/08\/svedska-skupina-abba-si-podmanila-svet.jpg","contentUrl":"https:\/\/regbu.com\/wp-content\/uploads\/2023\/08\/svedska-skupina-abba-si-podmanila-svet.jpg","width":1200,"height":677,"caption":"\u0160v\u00e9dsk\u00e1 skupina ABBA si podmanila sv\u011bt"},{"@type":"BreadcrumbList","@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/regbu.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u0160v\u00e9dsk\u00e1 skupina ABBA si podmanila sv\u011bt"}]},{"@type":"WebSite","@id":"https:\/\/regbu.com\/en\/#website","url":"https:\/\/regbu.com\/en\/","name":"REGBU.COM","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regbu.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/regbu.com\/en\/#\/schema\/person\/94ea9deda2629771b8a9ced002f6784e","name":"George Martin","url":"https:\/\/regbu.com\/fr\/author\/george-martin\/"},{"@type":"Question","@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259503253","position":1,"url":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259503253","name":"Quels sont les albums c\u00e9l\u00e8bres sortis avant 1977 ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Byla to hudebn\u00ed alba Ring Ring, Waterloo, ABBA, Arrival a The Album.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"},{"@type":"Question","@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259509855","position":2,"url":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259509855","name":"Quels sont les albums que le groupe a sortis apr\u00e8s 1977 ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"V\u0161e za\u010dalo v roce 1979 albem Voulez-Vous. N\u00e1sledovala alba jako Super Trouper, The Visitors a v neposledn\u00ed \u0159ad\u011b Voyage z roku 2011.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"},{"@type":"Question","@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259520352","position":3,"url":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259520352","name":"Quelle a \u00e9t\u00e9 la derni\u00e8re compilation du groupe ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Tato kompilace z roku 1982 nesla n\u00e1zev The Singles: The First Ten Years.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"},{"@type":"Question","@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259527820","position":4,"url":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259527820","name":"Quelles sont les autres chansons c\u00e9l\u00e8bres et populaires ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Zapom\u00ednat bychom nem\u011bli na p\u00edsn\u011b Ring, Ring, Fernando, Does Your Mother Know, Honey, Honey a Lay All Your Love On Me.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"},{"@type":"Question","@id":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259535224","position":5,"url":"https:\/\/regbu.com\/fr\/le-groupe-suedois-abba-a-conquis-le-monde\/#faq-question-1692259535224","name":"Quels sont les prix remport\u00e9s par ABBA ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Zm\u00ednka mus\u00ed padnout o Rockbj\u00f6rnen for the century's Swedish group\/artist z roku 1999 a Musikexportpriset z roku 2021.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/regbu.com\/fr\/wp-json\/wp\/v2\/posts\/1536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regbu.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regbu.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regbu.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/regbu.com\/fr\/wp-json\/wp\/v2\/comments?post=1536"}],"version-history":[{"count":2,"href":"https:\/\/regbu.com\/fr\/wp-json\/wp\/v2\/posts\/1536\/revisions"}],"predecessor-version":[{"id":1564,"href":"https:\/\/regbu.com\/fr\/wp-json\/wp\/v2\/posts\/1536\/revisions\/1564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regbu.com\/fr\/wp-json\/wp\/v2\/media\/1537"}],"wp:attachment":[{"href":"https:\/\/regbu.com\/fr\/wp-json\/wp\/v2\/media?parent=1536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regbu.com\/fr\/wp-json\/wp\/v2\/categories?post=1536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regbu.com\/fr\/wp-json\/wp\/v2\/tags?post=1536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}