{"id":1111,"date":"2023-07-17T14:13:34","date_gmt":"2023-07-17T12:13:34","guid":{"rendered":"https:\/\/regbu.com\/?p=1111"},"modified":"2025-09-05T07:40:59","modified_gmt":"2025-09-05T05:40:59","slug":"the-beatles-je-legenda-mezi-legendami","status":"publish","type":"post","link":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/","title":{"rendered":"The Beatles on legend legendide seas"},"content":{"rendered":"<p class=\"wp-block-paragraph\">The Beatles je n\u00e1zev anglick\u00e9 rockov\u00e9 kapely, kterou zn\u00e1 bezpochyby ka\u017ed\u00fd. V\u00a0dob\u00e1ch jej\u00ed nejv\u011bt\u0161\u00ed sl\u00e1vy ji milovali snad v\u0161ichni na sv\u011bt\u011b. Podobnou popularitu m\u011bl mimochodem <strong><a href=\"https:\/\/regbu.com\/et\/freddie-mercury-kuulsaim-laulja\/\">Freddie Mercury<\/a><\/strong>. Hudebn\u00ed skupina z\u00a0Liverpoolu dobyla sv\u011bt nejenom sv\u00fdm charismatick\u00fdm vystupov\u00e1n\u00edm, ale p\u0159edev\u0161\u00edm zp\u011bvem. Z\u00e1klad tvo\u0159ili \u010dty\u0159i zp\u011bv\u00e1ci.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>John Lennon<\/li>\n\n\n\n<li>Paul McCartney<\/li>\n\n\n\n<li>George Harrison<\/li>\n\n\n\n<li>Ringo Starr<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Jedno bic\u00ed, basov\u00e1 kytara, s\u00f3lov\u00e1 kytara a doprovodn\u00e1 kytara. Z\u00e1klad, k&nbsp;n\u011bmu\u017e se p\u0159idaly v\u00fdjime\u010dn\u00e9 texty spou\u0161t\u011bj\u00edc\u00ed lavinu obl\u00edbenosti a \u0161\u00edlenstv\u00ed. P\u0159esn\u011b takov\u00ed byli The Beatles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Jak to bylo s&nbsp;hudebn\u00ed skupinou?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Anglick\u00fd rock a pop v&nbsp;pod\u00e1n\u00ed t\u011bchto velik\u00e1n\u016f p\u0159il\u00e1kal velk\u00e9 mno\u017estv\u00ed fanou\u0161k\u016f. Styl v&nbsp;pod\u00e1n\u00ed psychedelick\u00e9 hudby a beatu byl v\u0161em \u010dty\u0159em \u010dlen\u016fm vlastn\u00ed po celou dobu jejich aktivn\u00edch rok\u016f. B\u011bhem kari\u00e9ry spolupracovali The Beatles s&nbsp;vydavatelstv\u00edmi typu <em>Parlophone, Polydor, Capitol<\/em> a dal\u0161\u00edmi.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>P\u0159edm\u011bt<\/strong><\/td><td><strong>Teave<\/strong><\/td><\/tr><tr><td>Aktivn\u00ed roky<\/td><td>1957 a\u017e 1970<\/td><\/tr><tr><td>Asutaja<\/td><td>John Lennon<\/td><\/tr><tr><td>P\u0159esun do USA<\/td><td>60. l\u00e9ta minul\u00e9ho stolet\u00ed<\/td><\/tr><tr><td>Tv\u016fr\u010d\u00ed producent<\/td><td>George Martin<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Z\u00e1kladn\u00ed informace t\u00fdkaj\u00edc\u00ed se slavn\u00e9 hudebn\u00ed skupiny.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Kapela za sv\u00e9 p\u00edsn\u011b a alba z\u00edskala mnoh\u00e1 ocen\u011bn\u00ed. \u0160lo prim\u00e1rn\u011b o ceny Grammy. Nap\u0159\u00edklad Grammy Trustees Award, cenu pro nejlep\u0161\u00edho um\u011blce, za nejlep\u0161\u00ed popov\u00e9 vok\u00e1ln\u00ed album a jin\u00e1. \u00dasp\u011bch na sebe v&nbsp;tomto p\u0159\u00edpad\u011b nenechal dlouho \u010dekat.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">The Beatles a jejich nejslavn\u011bj\u0161\u00ed songy<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A jak\u00e1 v\u00fdznamn\u00e1 d\u00edla se podepsala na zna\u010dn\u00e9 popularit\u011b hudebn\u00ed skupiny po cel\u00e9m sv\u011bt\u011b? P\u00edse\u0148 s&nbsp;n\u00e1zvem <strong>Eile v\u00f5i olgu see umbes<\/strong> nen\u00ed t\u0159eba komukoliv zdlouhav\u011b p\u0159edstavovat. Fanou\u0161ci rockov\u00e9 hudby maj\u00ed jist\u011b v&nbsp;pov\u011bdom\u00ed i Strawberry Fields Forever. V&nbsp;podstat\u011b ka\u017ed\u00e9 album p\u0159id\u00e1valo kapele na sl\u00e1v\u011b. K&nbsp;t\u011bm legend\u00e1rn\u00edm pat\u0159\u00ed nap\u0159\u00edklad album Revolver a osm\u00e9 album Sgt. Pepper&#8217;s Lonely Hearts Club Band.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Z\u00e1nik The Beatles p\u0159i\u0161el s&nbsp;rozpadem kapely v&nbsp;okam\u017eiku, kdy se jej\u00ed \u010dlenov\u00e9 vydali na s\u00f3lov\u00e9 dr\u00e1hy. I kdy\u017e se spekulovalo o budouc\u00edm <strong>seskupen\u00ed a znovuzrozen\u00ed<\/strong> hudebn\u00ed skupiny, p\u0159i\u0161la ne\u010dekan\u00e1 smrt Johna Lennona, kter\u00fd byl zast\u0159elen p\u0159ed domem. \u00dasp\u011bch kapely p\u0159ipom\u00edn\u00e1 hv\u011bzda na Hollywoodsk\u00e9m chodn\u00edku sl\u00e1vy.<\/p>","protected":false},"excerpt":{"rendered":"<p>The Beatles je n\u00e1zev anglick\u00e9 rockov\u00e9 kapely, kterou zn\u00e1 bezpochyby ka\u017ed\u00fd. V\u00a0dob\u00e1ch jej\u00ed nejv\u011bt\u0161\u00ed sl\u00e1vy ji milovali snad v\u0161ichni na sv\u011bt\u011b. Podobnou popularitu m\u011bl mimochodem Freddie Mercury. Hudebn\u00ed skupina z\u00a0Liverpoolu dobyla sv\u011bt nejenom sv\u00fdm charismatick\u00fdm vystupov\u00e1n\u00edm, ale p\u0159edev\u0161\u00edm zp\u011bvem. Z\u00e1klad tvo\u0159ili \u010dty\u0159i zp\u011bv\u00e1ci. Jedno bic\u00ed, basov\u00e1 kytara, s\u00f3lov\u00e1 kytara a &hellip; <\/p>","protected":false},"author":2,"featured_media":1112,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[1223,1220,108,1218,136,1222,1219,1221,113,1217],"class_list":["post-1111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hudba","tag-anglicka-kapela","tag-george-harrison","tag-hudebni-skupina","tag-johl-lennon","tag-kapela","tag-liverpool","tag-paul-mccartney","tag-ringo-starr","tag-rock","tag-the-beatles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Beatles je legenda mezi legendami - REGBU.COM<\/title>\n<meta name=\"description\" content=\"Poznejte slavnou hudebn\u00ed skupinu The Beatles do nejmen\u0161\u00edho detailu. Zjist\u011bte o t\u011bchto legend\u00e1ch co nejv\u00edce informac\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Beatles je legenda mezi legendami - REGBU.COM\" \/>\n<meta property=\"og:description\" content=\"Poznejte slavnou hudebn\u00ed skupinu The Beatles do nejmen\u0161\u00edho detailu. Zjist\u011bte o t\u011bchto legend\u00e1ch co nejv\u00edce informac\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/\" \/>\n<meta property=\"og:site_name\" content=\"REGBU.COM\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-17T12:13:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T05:40:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regbu.com\/wp-content\/uploads\/2023\/07\/the-beatles-je-legenda-mezi-legendami.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"677\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"George Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Kirjutanud\" \/>\n\t<meta name=\"twitter:data1\" content=\"George Martin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Eeldatav lugemisaeg\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutit\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/\"},\"author\":{\"name\":\"George Martin\",\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#\\\/schema\\\/person\\\/94ea9deda2629771b8a9ced002f6784e\"},\"headline\":\"The Beatles je legenda mezi legendami\",\"datePublished\":\"2023-07-17T12:13:34+00:00\",\"dateModified\":\"2025-09-05T05:40:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/\"},\"wordCount\":431,\"image\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/the-beatles-je-legenda-mezi-legendami.jpg\",\"keywords\":[\"anglick\u00e1 kapela\",\"George Harrison\",\"hudebn\u00ed skupina\",\"Johl Lennon\",\"kapela\",\"Liverpool\",\"Paul McCartney\",\"Ringo Starr\",\"rock\",\"The Beatles\"],\"articleSection\":[\"Hudba\"],\"inLanguage\":\"et\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/\",\"url\":\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/\",\"name\":\"The Beatles je legenda mezi legendami - REGBU.COM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/the-beatles-je-legenda-mezi-legendami.jpg\",\"datePublished\":\"2023-07-17T12:13:34+00:00\",\"dateModified\":\"2025-09-05T05:40:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#\\\/schema\\\/person\\\/94ea9deda2629771b8a9ced002f6784e\"},\"description\":\"Poznejte slavnou hudebn\u00ed skupinu The Beatles do nejmen\u0161\u00edho detailu. Zjist\u011bte o t\u011bchto legend\u00e1ch co nejv\u00edce informac\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/the-beatles-je-legenda-mezi-legendami.jpg\",\"contentUrl\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/the-beatles-je-legenda-mezi-legendami.jpg\",\"width\":1200,\"height\":677,\"caption\":\"The Beatles je legenda mezi legendami\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regbu.com\\\/et\\\/the-beatles-is-legend-among-legends\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/regbu.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Beatles je legenda mezi legendami\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/regbu.com\\\/en\\\/\",\"name\":\"REGBU.COM\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regbu.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#\\\/schema\\\/person\\\/94ea9deda2629771b8a9ced002f6784e\",\"name\":\"George Martin\",\"url\":\"https:\\\/\\\/regbu.com\\\/et\\\/author\\\/george-martin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Beatles on legend legendide seas - REGBU.COM","description":"Poznejte slavnou hudebn\u00ed skupinu The Beatles do nejmen\u0161\u00edho detailu. Zjist\u011bte o t\u011bchto legend\u00e1ch co nejv\u00edce informac\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/","og_locale":"et_EE","og_type":"article","og_title":"The Beatles je legenda mezi legendami - REGBU.COM","og_description":"Poznejte slavnou hudebn\u00ed skupinu The Beatles do nejmen\u0161\u00edho detailu. Zjist\u011bte o t\u011bchto legend\u00e1ch co nejv\u00edce informac\u00ed.","og_url":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/","og_site_name":"REGBU.COM","article_published_time":"2023-07-17T12:13:34+00:00","article_modified_time":"2025-09-05T05:40:59+00:00","og_image":[{"width":1200,"height":677,"url":"https:\/\/regbu.com\/wp-content\/uploads\/2023\/07\/the-beatles-je-legenda-mezi-legendami.jpg","type":"image\/jpeg"}],"author":"George Martin","twitter_card":"summary_large_image","twitter_misc":{"Kirjutanud":"George Martin","Eeldatav lugemisaeg":"2 minutit"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/#article","isPartOf":{"@id":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/"},"author":{"name":"George Martin","@id":"https:\/\/regbu.com\/en\/#\/schema\/person\/94ea9deda2629771b8a9ced002f6784e"},"headline":"The Beatles je legenda mezi legendami","datePublished":"2023-07-17T12:13:34+00:00","dateModified":"2025-09-05T05:40:59+00:00","mainEntityOfPage":{"@id":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/"},"wordCount":431,"image":{"@id":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/#primaryimage"},"thumbnailUrl":"https:\/\/regbu.com\/wp-content\/uploads\/2023\/07\/the-beatles-je-legenda-mezi-legendami.jpg","keywords":["anglick\u00e1 kapela","George Harrison","hudebn\u00ed skupina","Johl Lennon","kapela","Liverpool","Paul McCartney","Ringo Starr","rock","The Beatles"],"articleSection":["Hudba"],"inLanguage":"et"},{"@type":"WebPage","@id":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/","url":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/","name":"The Beatles on legend legendide seas - REGBU.COM","isPartOf":{"@id":"https:\/\/regbu.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/#primaryimage"},"image":{"@id":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/#primaryimage"},"thumbnailUrl":"https:\/\/regbu.com\/wp-content\/uploads\/2023\/07\/the-beatles-je-legenda-mezi-legendami.jpg","datePublished":"2023-07-17T12:13:34+00:00","dateModified":"2025-09-05T05:40:59+00:00","author":{"@id":"https:\/\/regbu.com\/en\/#\/schema\/person\/94ea9deda2629771b8a9ced002f6784e"},"description":"Poznejte slavnou hudebn\u00ed skupinu The Beatles do nejmen\u0161\u00edho detailu. Zjist\u011bte o t\u011bchto legend\u00e1ch co nejv\u00edce informac\u00ed.","breadcrumb":{"@id":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/"]}]},{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/#primaryimage","url":"https:\/\/regbu.com\/wp-content\/uploads\/2023\/07\/the-beatles-je-legenda-mezi-legendami.jpg","contentUrl":"https:\/\/regbu.com\/wp-content\/uploads\/2023\/07\/the-beatles-je-legenda-mezi-legendami.jpg","width":1200,"height":677,"caption":"The Beatles je legenda mezi legendami"},{"@type":"BreadcrumbList","@id":"https:\/\/regbu.com\/et\/the-beatles-is-legend-among-legends\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/regbu.com\/en\/"},{"@type":"ListItem","position":2,"name":"The Beatles je legenda mezi legendami"}]},{"@type":"WebSite","@id":"https:\/\/regbu.com\/en\/#website","url":"https:\/\/regbu.com\/en\/","name":"REGBU.COM","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regbu.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"},{"@type":"Person","@id":"https:\/\/regbu.com\/en\/#\/schema\/person\/94ea9deda2629771b8a9ced002f6784e","name":"George Martin","url":"https:\/\/regbu.com\/et\/author\/george-martin\/"}]}},"_links":{"self":[{"href":"https:\/\/regbu.com\/et\/wp-json\/wp\/v2\/posts\/1111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regbu.com\/et\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regbu.com\/et\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regbu.com\/et\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/regbu.com\/et\/wp-json\/wp\/v2\/comments?post=1111"}],"version-history":[{"count":2,"href":"https:\/\/regbu.com\/et\/wp-json\/wp\/v2\/posts\/1111\/revisions"}],"predecessor-version":[{"id":1126,"href":"https:\/\/regbu.com\/et\/wp-json\/wp\/v2\/posts\/1111\/revisions\/1126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regbu.com\/et\/wp-json\/wp\/v2\/media\/1112"}],"wp:attachment":[{"href":"https:\/\/regbu.com\/et\/wp-json\/wp\/v2\/media?parent=1111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regbu.com\/et\/wp-json\/wp\/v2\/categories?post=1111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regbu.com\/et\/wp-json\/wp\/v2\/tags?post=1111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}