{"id":86,"date":"2022-01-02T07:35:34","date_gmt":"2022-01-02T06:35:34","guid":{"rendered":"https:\/\/regbu.com\/?p=86"},"modified":"2025-09-05T07:43:22","modified_gmt":"2025-09-05T05:43:22","slug":"svickova-na-smetane-si-podmani-vase-chute","status":"publish","type":"post","link":"https:\/\/regbu.com\/de\/svickova-auf-smetana-sie-schicken-ihre-geschmacker\/","title":{"rendered":"Die Scones auf Sahne werden Ihre Geschmacksnerven erobern"},"content":{"rendered":"<p class=\"wp-block-paragraph\">In einem unserer fr\u00fcheren Artikel haben wir Ihnen erkl\u00e4rt, wie man k\u00f6stliche <strong><a href=\"https:\/\/regbu.com\/de\/bramboracka-versuch-rezept-aus-babicky\/\">Kartoffelsuppe<\/a><\/strong> wie bei der Gro\u00dfmutter. Wenn Sie die Suppe zubereitet haben, ist es an der Zeit, mit dem Hauptgang zu beginnen. Wenn es sich um einen tschechischen Klassiker handelt, ist Ihr Ziel das Lendensteak auf Sahne. Wir zeigen Ihnen, wie Sie es von A bis Z zubereiten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Erforderliche Zutaten f\u00fcr die Zubereitung von Lebensmitteln<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Auch wenn es scheinen mag <strong>Lendenbraten in Sahne<\/strong> als ein sehr kompliziertes Gericht angesehen wird, ist das Gegenteil der Fall. Wenn Sie alle notwendigen Zutaten vorbereiten und die folgenden Anweisungen befolgen, k\u00f6nnen Sie dieses Gericht ganz einfach zubereiten. Die erforderlichen Zutaten finden Sie in der nachstehenden Tabelle.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Rohmaterial<\/strong><\/td><td><strong>Menge<\/strong><\/td><\/tr><tr><td>Br\u00fche<\/td><td>3 dl<\/td><\/tr><tr><td>Rinderlende<\/td><td>900 g<\/td><\/tr><tr><td>Wurzelgem\u00fcse<\/td><td>300 g<\/td><\/tr><tr><td>Glattes Mehl<\/td><td>3 Essl\u00f6ffel<\/td><\/tr><tr><td>Smetana<\/td><td>3 dl<\/td><\/tr><tr><td>Pflanzliches \u00d6l<\/td><td>3 Essl\u00f6ffel<\/td><\/tr><tr><td>Speck<\/td><td>50 g<\/td><\/tr><tr><td>Neue Gew\u00fcrze<\/td><td>4 St\u00fcck<\/td><\/tr><tr><td>Ganzer Pfeffer<\/td><td>4 St\u00fcck<\/td><\/tr><\/tbody><\/table><figcaption>Bereiten Sie alles vor, was Sie f\u00fcr das Rinderfilet in Sahne ben\u00f6tigen.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Zitronensaft, Lorbeerbl\u00e4tter, Cranberries und nicht zuletzt Zucker d\u00fcrfen in der Zutatenliste nicht fehlen. Sobald Sie all dies vorbereitet haben, k\u00f6nnen Sie mit dem Kochen beginnen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Biskuit auf Sahne Schritt f\u00fcr Schritt<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Bereiten Sie zun\u00e4chst das Fleisch vor. Den Speck w\u00fcrfeln und das Fleisch mit Salz w\u00fcrzen. Dann in den Ofen schieben und backen, bis <strong>knusprig gebraten<\/strong>. Wenn Sie das Fleisch herausnehmen, verwenden Sie den Speck, um das Filet selbst zuzubereiten. Braten Sie es zusammen mit dem Gem\u00fcse und den Zwiebeln an. Dann das Fleisch in die Mischung geben und erneut kochen. Vergessen Sie nicht, regelm\u00e4\u00dfig mit der Br\u00fche zu begie\u00dfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn das Fleisch fertig ist, nehmen Sie es heraus und beginnen Sie mit der Zubereitung der Sauce. F\u00fcr die Sahneso\u00dfe die So\u00dfe mit Mehl best\u00e4uben, die Sahne hinzuf\u00fcgen, mit den vorbereiteten Zutaten abschmecken und eine Weile k\u00f6cheln lassen. Es ist wichtig, die Mischung zu p\u00fcrieren und durch ein Sieb zu streichen, damit keine gro\u00dfen Klumpen in der Sauce bleiben. <strong>Dann k\u00f6nnen Sie anfangen zu servieren<\/strong>. Schneiden Sie das Fleisch in Scheiben und legen Sie es auf einen Teller. Eine klassische Beilage w\u00e4re ein Semmelkn\u00f6del. Dann die vorbereitete Lendensauce dar\u00fcber gie\u00dfen. Die Cranberries dienen als Dekoration f\u00fcr das Fleisch und als geschmackliche Erg\u00e4nzung. Alles zusammen wird au\u00dfergew\u00f6hnlich harmonisch sein und Sie werden es sicher genie\u00dfen.<\/p>","protected":false},"excerpt":{"rendered":"<p>In einem unserer fr\u00fcheren Artikel haben wir Ihnen gezeigt, wie Sie eine k\u00f6stliche Kartoffelsuppe wie bei Oma zubereiten k\u00f6nnen. Nachdem Sie nun die Suppe zubereitet haben, ist es an der Zeit, mit dem Hauptgericht zu beginnen. Wenn es um tschechische Klassiker geht, ist Ihr Ziel das Lendensteak auf Sahne. Wir zeigen Ihnen, wie Sie es von A bis Z zubereiten. Die notwendigen Zutaten ... <\/p>","protected":false},"author":2,"featured_media":87,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[45,46,20,21,34,36,47,48,49],"class_list":["post-86","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vareni","tag-houskovy-knedlik","tag-hovezi-svickova","tag-omacka","tag-pokrm","tag-prava-svickova","tag-svickova","tag-svickova-na-smetane","tag-svickova-omacka","tag-zelenina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sv\u00ed\u010dkov\u00e1 na smetan\u011b si podman\u00ed Va\u0161e chut\u011b - REGBU.COM<\/title>\n<meta name=\"description\" content=\"Sv\u00ed\u010dkov\u00e1 na smetan\u011b polahod\u00ed Va\u0161e chu\u0165ov\u00e9 poh\u00e1rky. V\u017edy\u0165 pr\u00e1v\u011b tento pokrm pat\u0159\u00ed k t\u011bm \u010desk\u00fdm tradi\u010dn\u00edm. Nau\u010dte se ji p\u0159ipravovat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/regbu.com\/de\/svickova-auf-smetana-sie-schicken-ihre-geschmacker\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sv\u00ed\u010dkov\u00e1 na smetan\u011b si podman\u00ed Va\u0161e chut\u011b - REGBU.COM\" \/>\n<meta property=\"og:description\" content=\"Sv\u00ed\u010dkov\u00e1 na smetan\u011b polahod\u00ed Va\u0161e chu\u0165ov\u00e9 poh\u00e1rky. V\u017edy\u0165 pr\u00e1v\u011b tento pokrm pat\u0159\u00ed k t\u011bm \u010desk\u00fdm tradi\u010dn\u00edm. Nau\u010dte se ji p\u0159ipravovat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/regbu.com\/de\/svickova-auf-smetana-sie-schicken-ihre-geschmacker\/\" \/>\n<meta property=\"og:site_name\" content=\"REGBU.COM\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-02T06:35:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T05:43:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/regbu.com\/wp-content\/uploads\/2022\/01\/svickova-na-smetane-si-podmani-vase-chute.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"George Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"George Martin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/\"},\"author\":{\"name\":\"George Martin\",\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#\\\/schema\\\/person\\\/94ea9deda2629771b8a9ced002f6784e\"},\"headline\":\"Sv\u00ed\u010dkov\u00e1 na smetan\u011b si podman\u00ed Va\u0161e chut\u011b\",\"datePublished\":\"2022-01-02T06:35:34+00:00\",\"dateModified\":\"2025-09-05T05:43:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/\"},\"wordCount\":455,\"image\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/svickova-na-smetane-si-podmani-vase-chute.jpg\",\"keywords\":[\"houskov\u00fd knedl\u00edk\",\"hov\u011bz\u00ed sv\u00ed\u010dkov\u00e1\",\"om\u00e1\u010dka\",\"pokrm\",\"prav\u00e1 sv\u00ed\u010dkov\u00e1\",\"sv\u00ed\u010dkov\u00e1\",\"sv\u00ed\u010dkov\u00e1 na smetan\u011b\",\"sv\u00ed\u010dkov\u00e1 om\u00e1\u010dka\",\"zelenina\"],\"articleSection\":[\"Va\u0159en\u00ed\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/\",\"url\":\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/\",\"name\":\"Sv\u00ed\u010dkov\u00e1 na smetan\u011b si podman\u00ed Va\u0161e chut\u011b - REGBU.COM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/svickova-na-smetane-si-podmani-vase-chute.jpg\",\"datePublished\":\"2022-01-02T06:35:34+00:00\",\"dateModified\":\"2025-09-05T05:43:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#\\\/schema\\\/person\\\/94ea9deda2629771b8a9ced002f6784e\"},\"description\":\"Sv\u00ed\u010dkov\u00e1 na smetan\u011b polahod\u00ed Va\u0161e chu\u0165ov\u00e9 poh\u00e1rky. V\u017edy\u0165 pr\u00e1v\u011b tento pokrm pat\u0159\u00ed k t\u011bm \u010desk\u00fdm tradi\u010dn\u00edm. Nau\u010dte se ji p\u0159ipravovat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/#primaryimage\",\"url\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/svickova-na-smetane-si-podmani-vase-chute.jpg\",\"contentUrl\":\"https:\\\/\\\/regbu.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/svickova-na-smetane-si-podmani-vase-chute.jpg\",\"width\":1200,\"height\":678,\"caption\":\"Sv\u00ed\u010dkov\u00e1 na smetan\u011b si podman\u00ed Va\u0161e chut\u011b\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/regbu.com\\\/svickova-na-smetane-si-podmani-vase-chute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/regbu.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sv\u00ed\u010dkov\u00e1 na smetan\u011b si podman\u00ed Va\u0161e chut\u011b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/regbu.com\\\/en\\\/\",\"name\":\"REGBU.COM\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/regbu.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/regbu.com\\\/en\\\/#\\\/schema\\\/person\\\/94ea9deda2629771b8a9ced002f6784e\",\"name\":\"George Martin\",\"url\":\"https:\\\/\\\/regbu.com\\\/de\\\/author\\\/george-martin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sahnekekse werden Ihre Geschmacksnerven erobern - REGBU.COM","description":"Die Scones auf Sahne werden Ihre Geschmacksnerven erfreuen. Schlie\u00dflich geh\u00f6rt dieses Gericht zu den traditionellen tschechischen Gerichten. Lernen Sie, wie man es zubereitet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/regbu.com\/de\/svickova-auf-smetana-sie-schicken-ihre-geschmacker\/","og_locale":"de_DE","og_type":"article","og_title":"Sv\u00ed\u010dkov\u00e1 na smetan\u011b si podman\u00ed Va\u0161e chut\u011b - REGBU.COM","og_description":"Sv\u00ed\u010dkov\u00e1 na smetan\u011b polahod\u00ed Va\u0161e chu\u0165ov\u00e9 poh\u00e1rky. V\u017edy\u0165 pr\u00e1v\u011b tento pokrm pat\u0159\u00ed k t\u011bm \u010desk\u00fdm tradi\u010dn\u00edm. Nau\u010dte se ji p\u0159ipravovat.","og_url":"https:\/\/regbu.com\/de\/svickova-auf-smetana-sie-schicken-ihre-geschmacker\/","og_site_name":"REGBU.COM","article_published_time":"2022-01-02T06:35:34+00:00","article_modified_time":"2025-09-05T05:43:22+00:00","og_image":[{"width":1200,"height":678,"url":"https:\/\/regbu.com\/wp-content\/uploads\/2022\/01\/svickova-na-smetane-si-podmani-vase-chute.jpg","type":"image\/jpeg"}],"author":"George Martin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"George Martin","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/#article","isPartOf":{"@id":"https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/"},"author":{"name":"George Martin","@id":"https:\/\/regbu.com\/en\/#\/schema\/person\/94ea9deda2629771b8a9ced002f6784e"},"headline":"Sv\u00ed\u010dkov\u00e1 na smetan\u011b si podman\u00ed Va\u0161e chut\u011b","datePublished":"2022-01-02T06:35:34+00:00","dateModified":"2025-09-05T05:43:22+00:00","mainEntityOfPage":{"@id":"https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/"},"wordCount":455,"image":{"@id":"https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/#primaryimage"},"thumbnailUrl":"https:\/\/regbu.com\/wp-content\/uploads\/2022\/01\/svickova-na-smetane-si-podmani-vase-chute.jpg","keywords":["houskov\u00fd knedl\u00edk","hov\u011bz\u00ed sv\u00ed\u010dkov\u00e1","om\u00e1\u010dka","pokrm","prav\u00e1 sv\u00ed\u010dkov\u00e1","sv\u00ed\u010dkov\u00e1","sv\u00ed\u010dkov\u00e1 na smetan\u011b","sv\u00ed\u010dkov\u00e1 om\u00e1\u010dka","zelenina"],"articleSection":["Va\u0159en\u00ed"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/","url":"https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/","name":"Sahnekekse werden Ihre Geschmacksnerven erobern - REGBU.COM","isPartOf":{"@id":"https:\/\/regbu.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/#primaryimage"},"image":{"@id":"https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/#primaryimage"},"thumbnailUrl":"https:\/\/regbu.com\/wp-content\/uploads\/2022\/01\/svickova-na-smetane-si-podmani-vase-chute.jpg","datePublished":"2022-01-02T06:35:34+00:00","dateModified":"2025-09-05T05:43:22+00:00","author":{"@id":"https:\/\/regbu.com\/en\/#\/schema\/person\/94ea9deda2629771b8a9ced002f6784e"},"description":"Die Scones auf Sahne werden Ihre Geschmacksnerven erfreuen. Schlie\u00dflich geh\u00f6rt dieses Gericht zu den traditionellen tschechischen Gerichten. Lernen Sie, wie man es zubereitet.","breadcrumb":{"@id":"https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/#primaryimage","url":"https:\/\/regbu.com\/wp-content\/uploads\/2022\/01\/svickova-na-smetane-si-podmani-vase-chute.jpg","contentUrl":"https:\/\/regbu.com\/wp-content\/uploads\/2022\/01\/svickova-na-smetane-si-podmani-vase-chute.jpg","width":1200,"height":678,"caption":"Sv\u00ed\u010dkov\u00e1 na smetan\u011b si podman\u00ed Va\u0161e chut\u011b"},{"@type":"BreadcrumbList","@id":"https:\/\/regbu.com\/svickova-na-smetane-si-podmani-vase-chute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/regbu.com\/en\/"},{"@type":"ListItem","position":2,"name":"Sv\u00ed\u010dkov\u00e1 na smetan\u011b si podman\u00ed Va\u0161e chut\u011b"}]},{"@type":"WebSite","@id":"https:\/\/regbu.com\/en\/#website","url":"https:\/\/regbu.com\/en\/","name":"REGBU.COM","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/regbu.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/regbu.com\/en\/#\/schema\/person\/94ea9deda2629771b8a9ced002f6784e","name":"George Martin","url":"https:\/\/regbu.com\/de\/author\/george-martin\/"}]}},"_links":{"self":[{"href":"https:\/\/regbu.com\/de\/wp-json\/wp\/v2\/posts\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/regbu.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/regbu.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/regbu.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/regbu.com\/de\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":2,"href":"https:\/\/regbu.com\/de\/wp-json\/wp\/v2\/posts\/86\/revisions"}],"predecessor-version":[{"id":115,"href":"https:\/\/regbu.com\/de\/wp-json\/wp\/v2\/posts\/86\/revisions\/115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/regbu.com\/de\/wp-json\/wp\/v2\/media\/87"}],"wp:attachment":[{"href":"https:\/\/regbu.com\/de\/wp-json\/wp\/v2\/media?parent=86"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/regbu.com\/de\/wp-json\/wp\/v2\/categories?post=86"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/regbu.com\/de\/wp-json\/wp\/v2\/tags?post=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}